{"id":1212,"date":"2009-05-22T00:30:30","date_gmt":"2009-05-21T22:30:30","guid":{"rendered":"http:\/\/julietterobert.com\/blog\/?p=1212"},"modified":"2011-08-06T19:45:24","modified_gmt":"2011-08-06T17:45:24","slug":"benin-jour-1-et-2","status":"publish","type":"post","link":"https:\/\/julietterobert.com\/blog\/2009\/05\/22\/benin-jour-1-et-2\/","title":{"rendered":"B\u00c3\u00a9nin, jour 1 et 2"},"content":{"rendered":"<p>La nuit est tomb\u00c3\u00a9e tout d&rsquo;un coup, en trois ou quatre photos, un peu comme une enclume silencieuse qui ferait juste un petit poc. Il faisait jour et puis une photo plus tard, l&rsquo;autofocus patinait et j&rsquo;\u00c3\u00a9tais ? 1.4. Encore deux photos et quand j&rsquo;ai relev\u00c3\u00a9 le nez de mon viseur, il faisait nuit noire. C&rsquo;\u00c3\u00a9tait ma premi\u00c3\u00a8re soir\u00c3\u00a9e b\u00c3\u00a9ninoise et j&rsquo;avais d\u00c3\u00a9j\u00c3\u00a0 les yeux plein de cette terre ocre-orang\u00c3\u00a9e et du contraste avec le vert des bananeraies et des manguiers. En moins de vingt-quatre heures, je m&rsquo;\u00c3\u00a9tais d\u00c3\u00a9j\u00c3\u00a0 emm\u00c3\u00aal\u00c3\u00a9e les pinceaux dans le protocole en \u00c3\u00a9tant pr\u00c3\u00a9sent\u00c3\u00a9e \u00c3\u00a0 deux rois, j&rsquo;avais d\u00c3\u00a9j\u00c3\u00a0 assist\u00c3\u00a9 \u00c3\u00a0 un rituel vaudou auquel je ne comprenais rien et cens\u00c3\u00a9 donner force et vigueur, dans une case minuscule o\u00c3\u00b9? une pr\u00c3\u00aatresse m&rsquo;avait fait boire une eau \u00c3\u00a9trange et j&rsquo;\u00c3\u00a9tais d\u00c3\u00a9j\u00c3\u00a0 un peu impressionn\u00c3\u00a9e par le masque g\u00c3\u00a9ant du Zangbeto du village de Doutou.<br \/>\nC&rsquo;\u00c3\u00a9tait le premier jour et j&rsquo;ai surtout not\u00c3\u00a9 que la nuit tombait trop vite, un peu comme une enclume silencieuse qui ferait un petit poc.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/julietterobert.com\/blog\/images\/benin12.jpg\" alt=\"b\u00c3\u00a9nin adepte zangbeto doutou\" \/><br \/>\n<em>Un adepte du Zangbeto &#8211; Doutou, 09.01.2009<\/em><\/p>\n<p>Le deuxi\u00c3\u00a8me jour reste comme celui o\u00c3\u00b9 Simone est tomb\u00c3\u00a9e en rade apr\u00c3\u00a8s environ 72521 photos en 4 ans et m&rsquo;a laiss\u00c3\u00a9e en plan avec une f\u00c3\u00aate vaudoue \u00c3\u00a0 peine entam\u00c3\u00a9e sur les bras \u00c3\u00a0 couvrir au 35 ou 40mm, ce qui est un peu court. Cela \u00c3\u00a9tant, Simone a eu le bon go\u00c3\u00bbt de rendre l&rsquo;\u00c3\u00a2me apr\u00c3\u00a8s le sacrifice rituel d&rsquo;une vierge (ahem, une <strong>ch\u00c3\u00a8vre<\/strong> vierge) mais avant le d\u00c3\u00a9fil\u00c3\u00a9 des communaut\u00c3\u00a9s d&rsquo;adeptes. Pass\u00c3\u00a9e la rage qui a su retenir les larmes de d\u00c3\u00a9pit, en sueur et couverte de poussi\u00c3\u00a8re, il a fallu accepter le noir et blanc dans des conditions qui hurlaient \u00c3\u00a0 la couleur, aux rouges violents, aux violets \u00c3\u00a9clatants, aux verts tranchants, dans une mer orange.<br \/>\nLe deuxi\u00c3\u00a8me jour, Simone m&rsquo;a l\u00c3\u00a2ch\u00c3\u00a9e et j&rsquo;ai eu chaud et j&rsquo;ai eu le tournis, j&rsquo;ai eu mal au ventre et envie de pleurer au beau milieu de gens qui dansaient et chantaient dans une orgie de soleil et de couleurs, comme quoi, on peut pas tout contr\u00c3\u00b4ler.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/julietterobert.com\/blog\/images\/benin13.jpg\" alt=\"b\u00c3\u00a9nin f\u00c3\u00aate du vaudou 2009 com?\" \/><br \/>\n<em>Danses vaudoues &#8211; F?te des cultes Vaudous \u00c3\u00a0 Com\u00c3\u00a8, 10.01.2009<\/em><\/p>\n<p>Enfin bref, tout \u00c3\u00a7a pour dire que je commence enfin \u00c3\u00a0 mettre des photos de vaudou sur mon site, par <a href=\"http:\/\/julietterobert.com\/reportages\/vaudou-au-benin\/\">l\u00c3\u00a0<\/a>, que c&rsquo;est du noir et blanc par choix drastique et que la s\u00c3\u00a9lection fut draconienne selon des crit\u00c3\u00a8res \u00c3\u00a9videmment pas forc\u00c3\u00a9ment objectifs mais qui se tiennent au moins un petit peu.<\/p>\n<p>[dewplayer:http:\/\/julietterobert.com\/blog\/images\/hrsta.mp3]<br \/>\n<em>Hrsta &#8211; Une infinit\u00c3\u00a9 de trous en formes d&rsquo;hommes<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nuit est tomb\u00c3\u00a9e tout d&rsquo;un coup, en trois ou quatre photos, un peu comme une enclume silencieuse qui ferait juste un petit poc. Il faisait jour et puis une photo plus tard, l&rsquo;autofocus patinait et j&rsquo;\u00c3\u00a9tais ? 1.4. Encore deux photos et quand j&rsquo;ai relev\u00c3\u00a9 le nez de mon viseur, il faisait nuit noire. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,5],"tags":[18,28,81,27],"class_list":["post-1212","post","type-post","status-publish","format-standard","hentry","category-le-plus-hum-metier-du-monde","category-life-on-pause","tag-benin","tag-leica-m6","tag-simone","tag-vaudou"],"_links":{"self":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/1212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":3,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"predecessor-version":[{"id":1806,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/1212\/revisions\/1806"}],"wp:attachment":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/categories?post=1212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}