{"id":411,"date":"2004-07-23T01:17:32","date_gmt":"2004-07-23T00:17:32","guid":{"rendered":"\/?p=411"},"modified":"2004-07-23T01:17:32","modified_gmt":"2004-07-23T00:17:32","slug":"emone-day-49-5em","status":"publish","type":"post","link":"https:\/\/julietterobert.com\/blog\/2004\/07\/23\/emone-day-49-5em\/","title":{"rendered":"<em>One day 49 #5<\/em>"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/julietterobert.com\/blog\/images\/1day494.jpg\" border=\"0\" alt=\"one day 49\" \/><\/p>\n<p><em>i can&rsquo;t see properly, but that&rsquo;s the way my camera likes it<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>i can&rsquo;t see properly, but that&rsquo;s the way my camera likes it<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-411","post","type-post","status-publish","format-standard","hentry","category-life-on-pause"],"_links":{"self":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/comments?post=411"}],"version-history":[{"count":0,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/411\/revisions"}],"wp:attachment":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/media?parent=411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/categories?post=411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/tags?post=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}