{"id":52,"date":"2003-12-29T23:24:35","date_gmt":"2003-12-29T22:24:35","guid":{"rendered":"\/?p=52"},"modified":"2003-12-29T23:24:35","modified_gmt":"2003-12-29T22:24:35","slug":"spece-dartiste-gatee-va","status":"publish","type":"post","link":"https:\/\/julietterobert.com\/blog\/2003\/12\/29\/spece-dartiste-gatee-va\/","title":{"rendered":"s&rsquo;p?ce d&rsquo;artiste g?t?e, va !"},"content":{"rendered":"<p>et bien&#8230;puisque les h?ritages sont devenus des notions d?su?tes and obsol?tes, et que j&rsquo;ai quand m?me besoin de mat?riel, je propose qu&rsquo;on en revienne au m?c?nat.<\/p>\n<p>pour les m?c?nes modernes, j&rsquo;ai un compte paypal. <\/p>\n<p>merci d&rsquo;avance.<\/p>\n<p>:D<\/p>\n","protected":false},"excerpt":{"rendered":"<p>et bien&#8230;puisque les h?ritages sont devenus des notions d?su?tes and obsol?tes, et que j&rsquo;ai quand m?me besoin de mat?riel, je propose qu&rsquo;on en revienne au m?c?nat. pour les m?c?nes modernes, j&rsquo;ai un compte paypal. merci d&rsquo;avance. :D<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52","post","type-post","status-publish","format-standard","hentry","category-unfinished-thoughts"],"_links":{"self":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":0,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/52\/revisions"}],"wp:attachment":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/categories?post=52"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/tags?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}