{"id":963,"date":"2009-03-01T03:53:19","date_gmt":"2009-03-01T02:53:19","guid":{"rendered":"http:\/\/julietterobert.com\/blog\/?p=963"},"modified":"2011-08-07T16:03:50","modified_gmt":"2011-08-07T14:03:50","slug":"ceci-nest-pas-un-bug","status":"publish","type":"post","link":"https:\/\/julietterobert.com\/blog\/2009\/03\/01\/ceci-nest-pas-un-bug\/","title":{"rendered":"Ceci n&rsquo;est pas un bug"},"content":{"rendered":"<p>Non vous ne vous \u00c3\u00aates pas gour\u00c3\u00a9 de blog, j&rsquo;ai juste profit\u00c3\u00a9 de ce que j&rsquo;avais vraiment trop de taf pour passer encore du temps \u00c3\u00a0 tripatouiller dans la nouvelle version de WordPress. et accessoirement dans un nouveau layout. il ne va p&rsquo;tet pas rester en l&rsquo;\u00c3\u00a9tat, on verra. pis y&rsquo;a des nouveaux liens. bon, \u00c3\u00a7a manque de t\u00c3\u00a2ches de caf\u00c3\u00a9 mais \u00c3\u00a7a viendra s\u00c3\u00bbrement.<br \/>\nd\u00c3\u00a8s que je serais de nouveau surbook\u00c3\u00a9e, genre demain ou apr\u00c3\u00a8s-demain ou la semaine prochaine, je fais de nouveaux headers cons.<br \/>\nah oui, et je posterai de nouvelles photos aussi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non vous ne vous \u00c3\u00aates pas gour\u00c3\u00a9 de blog, j&rsquo;ai juste profit\u00c3\u00a9 de ce que j&rsquo;avais vraiment trop de taf pour passer encore du temps \u00c3\u00a0 tripatouiller dans la nouvelle version de WordPress. et accessoirement dans un nouveau layout. il ne va p&rsquo;tet pas rester en l&rsquo;\u00c3\u00a9tat, on verra. pis y&rsquo;a des nouveaux liens. bon, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[12,15,11,14,10],"class_list":["post-963","post","type-post","status-publish","format-standard","hentry","category-unfinished-thoughts","tag-bug","tag-mazette-il-se-fait-tard","tag-surmenage","tag-tag-qui-sert-a-rien","tag-wordpress"],"_links":{"self":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/comments?post=963"}],"version-history":[{"count":5,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/963\/revisions"}],"predecessor-version":[{"id":1843,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/posts\/963\/revisions\/1843"}],"wp:attachment":[{"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/media?parent=963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/categories?post=963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/julietterobert.com\/blog\/wp-json\/wp\/v2\/tags?post=963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}