{"id":8679,"date":"2025-02-11T12:25:22","date_gmt":"2025-02-11T11:25:22","guid":{"rendered":"https:\/\/julietterobert.com\/?p=8679"},"modified":"2025-02-11T12:25:22","modified_gmt":"2025-02-11T11:25:22","slug":"targeted-women","status":"publish","type":"post","link":"https:\/\/julietterobert.com\/en\/2025\/02\/targeted-women\/","title":{"rendered":"Targeted Women"},"content":{"rendered":"<script type=\"text\/javascript\">\/* <![CDATA[ *\/ psTimeout[404866]=4000;psAudio[404866]=false;psAutoplay[404866]=false;psDelay[404866]=0;psTrans[404866]='fade';psLoop[404866]=false;psCarouselSize[404866]=4;psSpeed[404866]=100;psPagerStyle[404866]='thumbs';psClickOpens[404866]='advance';\/* ]]> *\/<\/script><div id=\"slideshow-wrapper404866\" class=\"slideshow-wrapper clearfix centered fancygrid photoswipe toggle-closed fluid\"><a id=\"psprev404866\" href=\"javascript: void(0);\"><\/a><a id=\"psnext404866\" href=\"javascript: void(0);\"><\/a>\n\t\t<div class=\"psthumbs toggle-thumbs\"><div id=\"pager404866\" style=\"margin-left:10px;\" class=\"pager items clearfix proportional\"><div><span style=\"height:212px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FAA3-6-2000px-300x212.jpg\" alt=\"FAA3-6-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:209px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethPortraitDef-2000px-300x209.jpg\" alt=\"ElizabethPortraitDef-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:209px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethDossier2-2000px-300x209.jpg\" alt=\"ElizabethDossier2-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:213px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Elizabeth-Militantes-2000px-300x213.jpg\" alt=\"Elizabeth-Militantes-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:204px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Lodya-portrait-2000px-300x204.jpg\" alt=\"Lodya-portrait-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:209px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/JoCox-portraitdef-2000px-300x209.jpg\" alt=\"JoCox-portraitdef-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:211px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Mair-2000px-300x211.jpg\" alt=\"Mair-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:209px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/WestYokshire-2000px-300x209.jpg\" alt=\"WestYokshire-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:211px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizMetiers2-2000px-300x211.jpg\" alt=\"DatavizMetiers2-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:211px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/BertaCaceres-300x211.jpg\" alt=\"BertaCaceres thumbnail\" \/><\/span><\/div><div><span style=\"height:210px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizCause2-2000px-300x210.jpg\" alt=\"DatavizCause2-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:300px; width:210px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Dataviz-ages-2000px-210x300.jpg\" alt=\"Dataviz-ages-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:214px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FatimaAmiri-2000px-300x214.jpg\" alt=\"FatimaAmiri-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:211px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/CarteKaboul-2000px-300x211.jpg\" alt=\"CarteKaboul-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:220px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Education2-2000px-300x220.jpg\" alt=\"Education2-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:211px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DilmaFerreiraDef-300x211.jpg\" alt=\"DilmaFerreiraDef thumbnail\" \/><\/span><\/div><div><span style=\"height:210px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/VanesaCampos-2000px-300x210.jpg\" alt=\"VanesaCampos-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:216px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Manifs2-1-2000px-300x216.jpg\" alt=\"Manifs2-1-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:212px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/NareMphela-300x212.jpg\" alt=\"NareMphela thumbnail\" \/><\/span><\/div><div><span style=\"height:210px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/MemorialVanesa-2000px-300x210.jpg\" alt=\"MemorialVanesa-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:212px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ClemenciaCarabali-2000px-300x212.jpg\" alt=\"ClemenciaCarabali-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:211px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Jungle-2000px-300x211.jpg\" alt=\"Jungle-2000px thumbnail\" \/><\/span><\/div><div><span style=\"height:210px; width:300px;\"><span><\/span><img decoding=\"async\" style=\"margin-right:10px; margin-bottom:10px;\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Carte-Colombie2-2000px-300x210.jpg\" alt=\"Carte-Colombie2-2000px thumbnail\" \/><\/span><\/div><\/div><!--.pager--><\/div><!--.psthumbs--><div id=\"portfolio-slideshow404866\" class=\"portfolio-slideshow showloader\">\n\t\t<div class=\"slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FAA3-6-2000px.jpg\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FAA3-6-2000px.jpg\" alt=\"FAA3-6-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FAA3-6-2000px.jpg\" alt=\"FAA3-6-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FAA3-6-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethPortraitDef-2000px.jpg\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethPortraitDef-2000px.jpg\" alt=\"ElizabethPortraitDef-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethPortraitDef-2000px.jpg\" alt=\"ElizabethPortraitDef-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethPortraitDef-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethDossier2-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"ElizabethDossier2-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethDossier2-2000px.jpg\" alt=\"ElizabethDossier2-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ElizabethDossier2-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Elizabeth-Militantes-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Elizabeth-Militantes-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Elizabeth-Militantes-2000px.jpg\" alt=\"Elizabeth-Militantes-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Elizabeth-Militantes-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Lodya-portrait-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Lodya-portrait-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Lodya-portrait-2000px.jpg\" alt=\"Lodya-portrait-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Lodya-portrait-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/JoCox-portraitdef-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"JoCox-portraitdef-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/JoCox-portraitdef-2000px.jpg\" alt=\"JoCox-portraitdef-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/JoCox-portraitdef-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Mair-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Mair-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Mair-2000px.jpg\" alt=\"Mair-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Mair-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/WestYokshire-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"WestYokshire-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/WestYokshire-2000px.jpg\" alt=\"WestYokshire-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/WestYokshire-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizMetiers2-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"DatavizMetiers2-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizMetiers2-2000px.jpg\" alt=\"DatavizMetiers2-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizMetiers2-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/BertaCaceres.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"BertaCaceres\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/BertaCaceres.jpg\" alt=\"BertaCaceres\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/BertaCaceres.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizCause2-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"DatavizCause2-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizCause2-2000px.jpg\" alt=\"DatavizCause2-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DatavizCause2-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Dataviz-ages-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Dataviz-ages-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Dataviz-ages-2000px.jpg\" alt=\"Dataviz-ages-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Dataviz-ages-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FatimaAmiri-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"FatimaAmiri-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FatimaAmiri-2000px.jpg\" alt=\"FatimaAmiri-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/FatimaAmiri-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/CarteKaboul-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"CarteKaboul-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/CarteKaboul-2000px.jpg\" alt=\"CarteKaboul-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/CarteKaboul-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Education2-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Education2-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Education2-2000px.jpg\" alt=\"Education2-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Education2-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DilmaFerreiraDef.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"DilmaFerreiraDef\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DilmaFerreiraDef.jpg\" alt=\"DilmaFerreiraDef\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/DilmaFerreiraDef.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/VanesaCampos-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"VanesaCampos-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/VanesaCampos-2000px.jpg\" alt=\"VanesaCampos-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/VanesaCampos-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Manifs2-1-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Manifs2-1-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Manifs2-1-2000px.jpg\" alt=\"Manifs2-1-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Manifs2-1-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/NareMphela.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"NareMphela\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/NareMphela.jpg\" alt=\"NareMphela\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/NareMphela.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/MemorialVanesa-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"MemorialVanesa-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/MemorialVanesa-2000px.jpg\" alt=\"MemorialVanesa-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/MemorialVanesa-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ClemenciaCarabali-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"ClemenciaCarabali-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ClemenciaCarabali-2000px.jpg\" alt=\"ClemenciaCarabali-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/ClemenciaCarabali-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Jungle-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Jungle-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Jungle-2000px.jpg\" alt=\"Jungle-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Jungle-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<div class=\"not-first slideshow-content\">\n\t\t<a href=\"javascript: void(0);\" class=\"slideshow-next\"><img decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Carte-Colombie2-2000px.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"Carte-Colombie2-2000px\" \/><noscript><img decoding=\"async\" src=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Carte-Colombie2-2000px.jpg\" alt=\"Carte-Colombie2-2000px\" \/><\/noscript><\/a><a href=\"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/Carte-Colombie2-2000px.jpg\" class=\"ps-photoswipe\" style=\"display:none\"><\/a><\/div><!-- .slideshow-content -->\n\t\t<\/div><!--#portfolio-slideshow--><div id=\"slideshow-meta404866\" class=\"slideshow-meta centered\"><div class=\"meta-content\"><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Elizabeth Ibrahim Ekaru, feminist activist for lands' rights in Kenya<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Grace Lolim, Zaina Combo and Rachael Mwikali.<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Lodya Albarti, iraqi activist now lives in hiding.<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Jo Cox, British MP.<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Thomas Mair, Jo Cox's murderer<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Kim Leadbeater, Jo Cox's sister who's now involved in politics.<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Berta Caceres, hondurian environmental activist<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Nearly half of the victims were defending women's rights.<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>30% of the victims were under 30 years old when they were killed and 41% were between 30 and 70 years old.<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Fatima Amiri, survivor of a terrorist attack in Afghanistan, lives in Turkey. <\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Dilma Ferreira, brazilian activist for the Amazonians rights. <\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Vanesa Campos, transgenders' rights activist<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Nare Mphela, south african transgenders' rights activist.<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Clemencia Carabali, afro-feminist leader in Colombia, presidential advisor for gender equality between 2022 and 2023<\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>Three Colombian activists in Cauca must stay anonymous for fear of reprisals. <\/p>\n<\/div><\/div><!-- .meta-content --><div class=\"meta-content not-first \"><div class=\"slideshow-description\"><p>On this map, the red crosses sewn represent the confirmed political feminicides, the white crosses represent suspicions of such a crime that should need to be more investigated.<\/p>\n<\/div><\/div><!-- .meta-content --><\/div><div id=\"slideshow-nav404866\" class=\"slideshow-nav graphical\"><a class=\"pause psp-icon psp-icon-replace\" data-icon=\"&#35;\" style=\"display:none\" href=\"javascript:void(0);\">Pause<\/a><a class=\"play psp-icon psp-icon-replace\" data-icon=\"&#34;\" href=\"javascript:void(0);\">Play<\/a><a class=\"restart psp-icon psp-icon-replace\" data-icon=\"&#34;\" style=\"display:none\" href=\"javascript: void(0);\">Play<\/a><a class=\"slideshow-prev psp-icon psp-icon-replace\" data-icon=\"&#37;\" href=\"javascript: void(0);\">Prev<\/a><span class=\"sep\">|<\/span><a class=\"slideshow-next psp-icon psp-icon-replace\" data-icon=\"&#38;\" href=\"javascript: void(0);\">Next<\/a><span class=\"thumb-toggles\"><a class=\"show psp-toggle psp-icon psp-icon-replace\" data-icon=\"&#33;\" href=\"javascript:void(0);\">Show thumbnails<\/a><a class=\"hide psp-toggle psp-icon psp-icon-replace\" data-icon=\"&#33;\" href=\"javascript:void(0);\">Hide thumbnails<\/a><\/span><a class=\"activate-fullscreen psp-icon psp-icon-replace\" data-icon=\"&#39;\" href=\"javascript:void(0);\" title=\"Activate fullscreen slideshow\">Fullscreen<\/a><\/div><!-- .slideshow-nav-->\n\t\t\t\t<\/div><!--#slideshow-wrapper-->\n<p>These women weren\u2019t leading  the same battles, walking in the same streets or speaking in the same forums. Yet they were all victims of the same crime:  political feminicide.<br \/>\nThese gender-based political assassinations are invisible crimes. They consist of killing women, both for the cause they are fighting for, and because they are women.<\/p>\n<p><a href=\"https:\/\/www.mediapart.fr\/journal\/dossier\/international\/femmes-abattre\">\u201cFemmes \u00e0 abattre\u201d<\/a> (Targeted Women) is the first journalistic investigation that has ever looked into these sexist crimes perpetrated all over the world. We\u2019ve gathered hundreds of texts, images and data in order to build a collective work that will help identifying the specific threats that women human rights activists are facing, and the mechanism of impunity that surrounds them.<br \/>\nPolitical feminicides are like \u201ccluster bombs\u201d. By committing these murders, perpetrators manage to silence the women who dared taking up the public voice. At the same time, they hang a sword of Damocles above the head of their successors, those who aim to take over their battle.<br \/>\nWhile women activists are more numerous than ever, it is urgent to document these crimes. This way, states, institutions and NGOs will provide better support to today\u2019s and tomorrow\u2019s activists. <\/p>\n<p>For this investigation, I&#8217;ve worked with various sources : archive photographs, excerpts from the court files, maps&#8230;  It was then necessary to give meaning and coherence to all of this. So I chose to make cyanotypes, with its characteristic indigo blue colour, then I superimposed and arranged them with an image processing software.<br \/>\nHere are the visuals of this investigation, finalist for the Visa d&#8217;Or for digital information at the Visa pour l&#8217;Image Festival in Perpignan in 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/www.mediapart.fr\/journal\/dossier\/international\/femmes-abattre\">\u201cFemmes \u00e0 abattre\u201d<\/a> (Targeted Women) is the first journalistic investigation that has ever looked into these sexist crimes perpetrated all over the world. We\u2019ve gathered hundreds of texts, images and data in order to build a collective work that will help identifying the specific threats that women human rights activists are facing, and the mechanism of impunity that surrounds them.<\/p>\n","protected":false},"author":1,"featured_media":8678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[515],"tags":[735],"class_list":["post-8679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stories","tag-feminicide-en"],"jetpack_featured_media_url":"https:\/\/julietterobert.com\/public\/wp-content\/uploads\/2025\/02\/img_fempol.jpg","jetpack_shortlink":"https:\/\/wp.me\/pGmqD-2fZ","_links":{"self":[{"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/posts\/8679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/comments?post=8679"}],"version-history":[{"count":4,"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/posts\/8679\/revisions"}],"predecessor-version":[{"id":8685,"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/posts\/8679\/revisions\/8685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/media\/8678"}],"wp:attachment":[{"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/media?parent=8679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/categories?post=8679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/julietterobert.com\/en\/wp-json\/wp\/v2\/tags?post=8679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}